{"id":439,"date":"2024-03-12T12:49:16","date_gmt":"2024-03-12T12:49:16","guid":{"rendered":"https:\/\/etherow-ibc.co.uk\/?page_id=439"},"modified":"2024-03-27T18:15:51","modified_gmt":"2024-03-27T18:15:51","slug":"short-mat-merit-winter-2023","status":"publish","type":"page","link":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/","title":{"rendered":"Short Mat Merit Results &#8211; Winter 2023"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_text_color=&#8221;#019585&#8243; header_font_size=&#8221;45px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Short Mat Merit Results &#8211; Winter 2023<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_3_line_height=&#8221;1.1em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024.<\/p>\n<p>After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The merit table order is based on the total points scored from a given player\u2019s best eight scores added together.<\/p>\n<p>The top four placed players in Winter 2023 were:<\/p>\n<ul>\n<li>Gary Williamson took first place winning \u00a340\u00a0<\/li>\n<li>John Cunningham was second and won \u00a330<\/li>\n<li>Steven Roberts finished in third place winning \u00a320<\/li>\n<li>Alan Booth came fourth and won \u00a310<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<table id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U\" class=\"igsv-table no-datatables general-gs-table\" lang=\"en-US\" style=\"\"><thead>\n<tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-1\" class=\"row-1 odd\"><th class=\"col-1 odd\"><div>Merit Standings After 16 Weeks<\/div><\/th><th class=\"col-2 even\"><div><\/div><\/th><th class=\"col-3 odd\"><div><\/div><\/th><th class=\"col-4 even\"><div><\/div><\/th><th class=\"col-5 odd\"><div><\/div><\/th><\/tr><\/thead><tbody>\n<tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-2\" class=\"row-2 even\"><td class=\"col-1 odd\"><\/td><td class=\"col-2 even\"><\/td><td class=\"col-3 odd\"><\/td><td class=\"col-4 even\"><\/td><td class=\"col-5 odd\"><\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-3\" class=\"row-3 odd\"><td class=\"col-1 odd\"><\/td><td class=\"col-2 even\">Weeks Played<\/td><td class=\"col-3 odd\">Total Points<\/td><td class=\"col-4 even\">Average Points<\/td><td class=\"col-5 odd\">Best 8 Scores<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-4\" class=\"row-4 even\"><td class=\"col-1 odd\">G. WIlliamson<\/td><td class=\"col-2 even\">15<\/td><td class=\"col-3 odd\">87<\/td><td class=\"col-4 even\">5.80<\/td><td class=\"col-5 odd\">58<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-5\" class=\"row-5 odd\"><td class=\"col-1 odd\">J. Cunningham<\/td><td class=\"col-2 even\">13<\/td><td class=\"col-3 odd\">60<\/td><td class=\"col-4 even\">4.62<\/td><td class=\"col-5 odd\">45<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-6\" class=\"row-6 even\"><td class=\"col-1 odd\">S. Roberts<\/td><td class=\"col-2 even\">9<\/td><td class=\"col-3 odd\">45<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">44<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-7\" class=\"row-7 odd\"><td class=\"col-1 odd\">A. Booth<\/td><td class=\"col-2 even\">8<\/td><td class=\"col-3 odd\">42<\/td><td class=\"col-4 even\">5.25<\/td><td class=\"col-5 odd\">42<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-8\" class=\"row-8 even\"><td class=\"col-1 odd\">A. Winstanley<\/td><td class=\"col-2 even\">9<\/td><td class=\"col-3 odd\">41<\/td><td class=\"col-4 even\">4.56<\/td><td class=\"col-5 odd\">40<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-9\" class=\"row-9 odd\"><td class=\"col-1 odd\">D. Almond<\/td><td class=\"col-2 even\">8<\/td><td class=\"col-3 odd\">40<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">40<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-10\" class=\"row-10 even\"><td class=\"col-1 odd\">D. Twigg<\/td><td class=\"col-2 even\">9<\/td><td class=\"col-3 odd\">38<\/td><td class=\"col-4 even\">4.22<\/td><td class=\"col-5 odd\">37<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-11\" class=\"row-11 odd\"><td class=\"col-1 odd\">A. Almond<\/td><td class=\"col-2 even\">8<\/td><td class=\"col-3 odd\">36<\/td><td class=\"col-4 even\">4.50<\/td><td class=\"col-5 odd\">36<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-12\" class=\"row-12 even\"><td class=\"col-1 odd\">P. Robinson<\/td><td class=\"col-2 even\">8<\/td><td class=\"col-3 odd\">36<\/td><td class=\"col-4 even\">4.50<\/td><td class=\"col-5 odd\">36<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-13\" class=\"row-13 odd\"><td class=\"col-1 odd\">A. Norbury<\/td><td class=\"col-2 even\">7<\/td><td class=\"col-3 odd\">33<\/td><td class=\"col-4 even\">4.71<\/td><td class=\"col-5 odd\">33<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-14\" class=\"row-14 even\"><td class=\"col-1 odd\">D. Lloyd<\/td><td class=\"col-2 even\">8<\/td><td class=\"col-3 odd\">33<\/td><td class=\"col-4 even\">4.13<\/td><td class=\"col-5 odd\">33<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-15\" class=\"row-15 odd\"><td class=\"col-1 odd\">C. Crowther<\/td><td class=\"col-2 even\">6<\/td><td class=\"col-3 odd\">31<\/td><td class=\"col-4 even\">5.17<\/td><td class=\"col-5 odd\">31<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-16\" class=\"row-16 even\"><td class=\"col-1 odd\">M. Douglass<\/td><td class=\"col-2 even\">10<\/td><td class=\"col-3 odd\">32<\/td><td class=\"col-4 even\">3.20<\/td><td class=\"col-5 odd\">30<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-17\" class=\"row-17 odd\"><td class=\"col-1 odd\">E. Hulme<\/td><td class=\"col-2 even\">7<\/td><td class=\"col-3 odd\">29<\/td><td class=\"col-4 even\">4.14<\/td><td class=\"col-5 odd\">29<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-18\" class=\"row-18 even\"><td class=\"col-1 odd\">D. Slater<\/td><td class=\"col-2 even\">6<\/td><td class=\"col-3 odd\">27<\/td><td class=\"col-4 even\">4.50<\/td><td class=\"col-5 odd\">27<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-19\" class=\"row-19 odd\"><td class=\"col-1 odd\">P. Norbury<\/td><td class=\"col-2 even\">6<\/td><td class=\"col-3 odd\">25<\/td><td class=\"col-4 even\">4.17<\/td><td class=\"col-5 odd\">25<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-20\" class=\"row-20 even\"><td class=\"col-1 odd\">D. Spilsbury<\/td><td class=\"col-2 even\">6<\/td><td class=\"col-3 odd\">23<\/td><td class=\"col-4 even\">3.83<\/td><td class=\"col-5 odd\">23<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-21\" class=\"row-21 odd\"><td class=\"col-1 odd\">D. Heatley<\/td><td class=\"col-2 even\">5<\/td><td class=\"col-3 odd\">22<\/td><td class=\"col-4 even\">4.40<\/td><td class=\"col-5 odd\">22<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-22\" class=\"row-22 even\"><td class=\"col-1 odd\">K. Stanley<\/td><td class=\"col-2 even\">5<\/td><td class=\"col-3 odd\">22<\/td><td class=\"col-4 even\">4.40<\/td><td class=\"col-5 odd\">22<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-23\" class=\"row-23 odd\"><td class=\"col-1 odd\">P. Hallows<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">20<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">20<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-24\" class=\"row-24 even\"><td class=\"col-1 odd\">A. Housley<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">6.33<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-25\" class=\"row-25 odd\"><td class=\"col-1 odd\">A. Potkins<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">4.75<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-26\" class=\"row-26 even\"><td class=\"col-1 odd\">D. Quinn<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">4.75<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-27\" class=\"row-27 odd\"><td class=\"col-1 odd\">J. Bannister<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">6.33<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-28\" class=\"row-28 even\"><td class=\"col-1 odd\">K. Baxter<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">6.33<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-29\" class=\"row-29 odd\"><td class=\"col-1 odd\">M. Dawson<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">4.75<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-30\" class=\"row-30 even\"><td class=\"col-1 odd\">M. McHugh<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">19<\/td><td class=\"col-4 even\">4.75<\/td><td class=\"col-5 odd\">19<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-31\" class=\"row-31 odd\"><td class=\"col-1 odd\">E. Young<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">17<\/td><td class=\"col-4 even\">4.25<\/td><td class=\"col-5 odd\">17<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-32\" class=\"row-32 even\"><td class=\"col-1 odd\">S. Atkinson<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">17<\/td><td class=\"col-4 even\">5.67<\/td><td class=\"col-5 odd\">17<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-33\" class=\"row-33 odd\"><td class=\"col-1 odd\">A. Roberts<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">15<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">15<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-34\" class=\"row-34 even\"><td class=\"col-1 odd\">J. Leung<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">15<\/td><td class=\"col-4 even\">3.75<\/td><td class=\"col-5 odd\">15<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-35\" class=\"row-35 odd\"><td class=\"col-1 odd\">P. Roberts<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">15<\/td><td class=\"col-4 even\">7.50<\/td><td class=\"col-5 odd\">15<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-36\" class=\"row-36 even\"><td class=\"col-1 odd\">I. Jones<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">14<\/td><td class=\"col-4 even\">7.00<\/td><td class=\"col-5 odd\">14<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-37\" class=\"row-37 odd\"><td class=\"col-1 odd\">R. Booth<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">13<\/td><td class=\"col-4 even\">6.50<\/td><td class=\"col-5 odd\">13<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-38\" class=\"row-38 even\"><td class=\"col-1 odd\">C. Cooper<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">12<\/td><td class=\"col-4 even\">6.00<\/td><td class=\"col-5 odd\">12<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-39\" class=\"row-39 odd\"><td class=\"col-1 odd\">J. Mitchell<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">11<\/td><td class=\"col-4 even\">5.50<\/td><td class=\"col-5 odd\">11<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-40\" class=\"row-40 even\"><td class=\"col-1 odd\">R. Goodwin<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">11<\/td><td class=\"col-4 even\">3.67<\/td><td class=\"col-5 odd\">11<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-41\" class=\"row-41 odd\"><td class=\"col-1 odd\">Gl. Jones<\/td><td class=\"col-2 even\">4<\/td><td class=\"col-3 odd\">10<\/td><td class=\"col-4 even\">2.50<\/td><td class=\"col-5 odd\">10<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-42\" class=\"row-42 even\"><td class=\"col-1 odd\">J. Young<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">10<\/td><td class=\"col-4 even\">3.33<\/td><td class=\"col-5 odd\">10<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-43\" class=\"row-43 odd\"><td class=\"col-1 odd\">K. Hewat<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">10<\/td><td class=\"col-4 even\">3.33<\/td><td class=\"col-5 odd\">10<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-44\" class=\"row-44 even\"><td class=\"col-1 odd\">J. Proctor<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">9<\/td><td class=\"col-4 even\">4.50<\/td><td class=\"col-5 odd\">9<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-45\" class=\"row-45 odd\"><td class=\"col-1 odd\">H. Carter<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">8<\/td><td class=\"col-4 even\">4.00<\/td><td class=\"col-5 odd\">8<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-46\" class=\"row-46 even\"><td class=\"col-1 odd\">R. Hewat<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">8<\/td><td class=\"col-4 even\">2.67<\/td><td class=\"col-5 odd\">8<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-47\" class=\"row-47 odd\"><td class=\"col-1 odd\">T. Stevens<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">8<\/td><td class=\"col-4 even\">8.00<\/td><td class=\"col-5 odd\">8<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-48\" class=\"row-48 even\"><td class=\"col-1 odd\">A. Crabtree<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">7<\/td><td class=\"col-4 even\">3.50<\/td><td class=\"col-5 odd\">7<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-49\" class=\"row-49 odd\"><td class=\"col-1 odd\">B. Nielsen<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">7<\/td><td class=\"col-4 even\">7.00<\/td><td class=\"col-5 odd\">7<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-50\" class=\"row-50 even\"><td class=\"col-1 odd\">Go. Jones<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">7<\/td><td class=\"col-4 even\">3.50<\/td><td class=\"col-5 odd\">7<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-51\" class=\"row-51 odd\"><td class=\"col-1 odd\">J. Brain<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">7<\/td><td class=\"col-4 even\">3.50<\/td><td class=\"col-5 odd\">7<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-52\" class=\"row-52 even\"><td class=\"col-1 odd\">J. Crowther<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">7<\/td><td class=\"col-4 even\">7.00<\/td><td class=\"col-5 odd\">7<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-53\" class=\"row-53 odd\"><td class=\"col-1 odd\">M. Anderson<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">7<\/td><td class=\"col-4 even\">7.00<\/td><td class=\"col-5 odd\">7<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-54\" class=\"row-54 even\"><td class=\"col-1 odd\">C. Lawther<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">6<\/td><td class=\"col-4 even\">6.00<\/td><td class=\"col-5 odd\">6<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-55\" class=\"row-55 odd\"><td class=\"col-1 odd\">J. Lax<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">6<\/td><td class=\"col-4 even\">6.00<\/td><td class=\"col-5 odd\">6<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-56\" class=\"row-56 even\"><td class=\"col-1 odd\">M. Ridgway<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">6<\/td><td class=\"col-4 even\">6.00<\/td><td class=\"col-5 odd\">6<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-57\" class=\"row-57 odd\"><td class=\"col-1 odd\">G. Critchley<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">5<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">5<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-58\" class=\"row-58 even\"><td class=\"col-1 odd\">J. Cooper<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">5<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">5<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-59\" class=\"row-59 odd\"><td class=\"col-1 odd\">M. Haddon<\/td><td class=\"col-2 even\">3<\/td><td class=\"col-3 odd\">5<\/td><td class=\"col-4 even\">1.67<\/td><td class=\"col-5 odd\">5<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-60\" class=\"row-60 even\"><td class=\"col-1 odd\">P. Nixon<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">5<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">5<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-61\" class=\"row-61 odd\"><td class=\"col-1 odd\">S. Fletcher<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">5<\/td><td class=\"col-4 even\">5.00<\/td><td class=\"col-5 odd\">5<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-62\" class=\"row-62 even\"><td class=\"col-1 odd\">A. Brideaux<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">4<\/td><td class=\"col-4 even\">4.00<\/td><td class=\"col-5 odd\">4<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-63\" class=\"row-63 odd\"><td class=\"col-1 odd\">S. Scrimgeour<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">4<\/td><td class=\"col-4 even\">4.00<\/td><td class=\"col-5 odd\">4<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-64\" class=\"row-64 even\"><td class=\"col-1 odd\">T. Morgan<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">4<\/td><td class=\"col-4 even\">4.00<\/td><td class=\"col-5 odd\">4<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-65\" class=\"row-65 odd\"><td class=\"col-1 odd\">G. Shaw<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">3<\/td><td class=\"col-4 even\">3.00<\/td><td class=\"col-5 odd\">3<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-66\" class=\"row-66 even\"><td class=\"col-1 odd\">G. Thackery<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">3<\/td><td class=\"col-4 even\">1.50<\/td><td class=\"col-5 odd\">3<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-67\" class=\"row-67 odd\"><td class=\"col-1 odd\">B. Smethurst<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">2<\/td><td class=\"col-4 even\">1.00<\/td><td class=\"col-5 odd\">2<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-68\" class=\"row-68 even\"><td class=\"col-1 odd\">E. Slaone<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">2<\/td><td class=\"col-4 even\">2.00<\/td><td class=\"col-5 odd\">2<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-69\" class=\"row-69 odd\"><td class=\"col-1 odd\">L. Fennell<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">2<\/td><td class=\"col-4 even\">2.00<\/td><td class=\"col-5 odd\">2<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-70\" class=\"row-70 even\"><td class=\"col-1 odd\">P. Atkinson<\/td><td class=\"col-2 even\">2<\/td><td class=\"col-3 odd\">2<\/td><td class=\"col-4 even\">1.00<\/td><td class=\"col-5 odd\">2<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-71\" class=\"row-71 odd\"><td class=\"col-1 odd\">T. Scrimgeour<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">2<\/td><td class=\"col-4 even\">2.00<\/td><td class=\"col-5 odd\">2<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-72\" class=\"row-72 even\"><td class=\"col-1 odd\">A. Edwards<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">1<\/td><td class=\"col-4 even\">1.00<\/td><td class=\"col-5 odd\">1<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-73\" class=\"row-73 odd\"><td class=\"col-1 odd\">A. Ridgway<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">1<\/td><td class=\"col-4 even\">1.00<\/td><td class=\"col-5 odd\">1<\/td><\/tr><tr id=\"igsv-1ZhNvbKmJsI8Ozx-kVVn0JcGvHQiZSwdSes0MAHuHH4U-row-74\" class=\"row-74 even\"><td class=\"col-1 odd\">G. Almond<\/td><td class=\"col-2 even\">1<\/td><td class=\"col-3 odd\">1<\/td><td class=\"col-4 even\">1.00<\/td><td class=\"col-5 odd\">1<\/td><\/tr><\/tbody><\/table><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Short Mat Merit Results &#8211; Winter 2023The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The merit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-439","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Etherow Indoor Bowling Centre - Bowling for all across Greater Manchester\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Short Mat Merit Results \u2013 Winter 2023 - Etherow Indoor Bowling Centre\" \/>\n\t\t<meta property=\"og:description\" content=\"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/EtherowRink.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/EtherowRink.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-12T12:49:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-27T18:15:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/etherowibc\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Short Mat Merit Results \u2013 Winter 2023 - Etherow Indoor Bowling Centre\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/EtherowRink.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/etherow-ibc.co.uk\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#listItem\",\"name\":\"Short Mat Merit Results &#8211; Winter 2023\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#listItem\",\"position\":2,\"name\":\"Short Mat Merit Results &#8211; Winter 2023\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/#organization\",\"name\":\"Etherow Indoor Bowling Centre\",\"description\":\"Bowling for all across Greater Manchester\",\"url\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-bowls.jpg\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/etherowibc\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#webpage\",\"url\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/\",\"name\":\"Short Mat Merit Results \\u2013 Winter 2023 - Etherow Indoor Bowling Centre\",\"description\":\"Short Mat Merit Results \\u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/index.php\\\/short-mat-merit-winter-2023\\\/#breadcrumblist\"},\"datePublished\":\"2024-03-12T12:49:16+00:00\",\"dateModified\":\"2024-03-27T18:15:51+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/#website\",\"url\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/\",\"name\":\"etherow-ibc.co.uk\",\"description\":\"Bowling for all across Greater Manchester\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/etherow-ibc.co.uk\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Short Mat Merit Results \u2013 Winter 2023 - Etherow Indoor Bowling Centre","description":"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The","canonical_url":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/etherow-ibc.co.uk#listItem","position":1,"name":"Home","item":"https:\/\/etherow-ibc.co.uk","nextItem":{"@type":"ListItem","@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#listItem","name":"Short Mat Merit Results &#8211; Winter 2023"}},{"@type":"ListItem","@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#listItem","position":2,"name":"Short Mat Merit Results &#8211; Winter 2023","previousItem":{"@type":"ListItem","@id":"https:\/\/etherow-ibc.co.uk#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/etherow-ibc.co.uk\/#organization","name":"Etherow Indoor Bowling Centre","description":"Bowling for all across Greater Manchester","url":"https:\/\/etherow-ibc.co.uk\/","logo":{"@type":"ImageObject","url":"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/cropped-bowls.jpg","@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/etherowibc"]},{"@type":"WebPage","@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#webpage","url":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/","name":"Short Mat Merit Results \u2013 Winter 2023 - Etherow Indoor Bowling Centre","description":"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/etherow-ibc.co.uk\/#website"},"breadcrumb":{"@id":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/#breadcrumblist"},"datePublished":"2024-03-12T12:49:16+00:00","dateModified":"2024-03-27T18:15:51+00:00"},{"@type":"WebSite","@id":"https:\/\/etherow-ibc.co.uk\/#website","url":"https:\/\/etherow-ibc.co.uk\/","name":"etherow-ibc.co.uk","description":"Bowling for all across Greater Manchester","inLanguage":"en-US","publisher":{"@id":"https:\/\/etherow-ibc.co.uk\/#organization"}}]},"og:locale":"en_US","og:site_name":"Etherow Indoor Bowling Centre - Bowling for all across Greater Manchester","og:type":"article","og:title":"Short Mat Merit Results \u2013 Winter 2023 - Etherow Indoor Bowling Centre","og:description":"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The","og:url":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/","og:image":"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/EtherowRink.png","og:image:secure_url":"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/EtherowRink.png","og:image:width":946,"og:image:height":557,"article:published_time":"2024-03-12T12:49:16+00:00","article:modified_time":"2024-03-27T18:15:51+00:00","article:publisher":"https:\/\/www.facebook.com\/etherowibc","twitter:card":"summary_large_image","twitter:title":"Short Mat Merit Results \u2013 Winter 2023 - Etherow Indoor Bowling Centre","twitter:description":"Short Mat Merit Results \u2013 Winter 2023 The winter 2023 Short Mat Order of Merit was played over 16 weeks until 1st March 2024. After each week, players earned between one and eight points, with 8 points awarded for a first place knockout win, down to a single point for finishing in 8th place. The","twitter:image":"https:\/\/etherow-ibc.co.uk\/wp-content\/uploads\/2023\/08\/EtherowRink.png"},"aioseo_meta_data":{"post_id":"439","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-12 12:44:14","updated":"2025-06-04 09:26:44","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/etherow-ibc.co.uk\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tShort Mat Merit Results \u2013 Winter 2023\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/etherow-ibc.co.uk"},{"label":"Short Mat Merit Results &#8211; Winter 2023","link":"https:\/\/etherow-ibc.co.uk\/index.php\/short-mat-merit-winter-2023\/"}],"_links":{"self":[{"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":4,"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/439\/revisions"}],"predecessor-version":[{"id":495,"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/439\/revisions\/495"}],"wp:attachment":[{"href":"https:\/\/etherow-ibc.co.uk\/index.php\/wp-json\/wp\/v2\/media?parent=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}